{"id":530,"date":"2021-07-26T14:53:47","date_gmt":"2021-07-26T14:53:47","guid":{"rendered":"https:\/\/www.rtconsultancy.nl\/?post_type=expertises&#038;p=530"},"modified":"2021-08-26T07:52:26","modified_gmt":"2021-08-26T07:52:26","slug":"security-en-crisismanagement-training","status":"publish","type":"expertises","link":"https:\/\/www.rtconsultancy.nl\/nl\/expertises\/security-en-crisismanagement-training\/","title":{"rendered":"Security awareness programma"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"530\" class=\"elementor elementor-530\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"expertises\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e05b272 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e05b272\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46407b5e\" data-id=\"46407b5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54f361c0 elementor-widget elementor-widget-text-editor\" data-id=\"54f361c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p class=\"wp-block-paragraph\">Een hoge betrokkenheid en het begrijpen waarom veiligheidsmaatregelen zijn ingevoerd, is voor iedere organisatie een issue. U heeft dan niet direct de behoefte aan een opleiding die uitgaat van een standaard programma en daarmee geen recht doet aan uw specifieke vraag. Een maatwerktraining, mystery visits of een workshop, die direct in de praktijk haar vruchten afwerpt en ondersteunend werkt aan uw bedrijfsvoering, past hier veel beter bij.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"template":"","class_list":["post-530","expertises","type-expertises","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Security awareness programma - RT Consultancy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.rtconsultancy.nl\/nl\/expertises\/security-en-crisismanagement-training\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Security awareness programma - RT Consultancy\" \/>\n<meta property=\"og:description\" content=\"Een hoge betrokkenheid en het begrijpen waarom veiligheidsmaatregelen zijn ingevoerd, is voor iedere organisatie een issue. U heeft dan niet direct de behoefte aan een opleiding die uitgaat van een standaard programma en daarmee geen recht doet aan uw specifieke vraag. Een maatwerktraining, mystery visits of een workshop, die direct in de praktijk haar vruchten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.rtconsultancy.nl\/nl\/expertises\/security-en-crisismanagement-training\/\" \/>\n<meta property=\"og:site_name\" content=\"RT Consultancy\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-26T07:52:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/expertises\\\/security-en-crisismanagement-training\\\/\",\"url\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/expertises\\\/security-en-crisismanagement-training\\\/\",\"name\":\"Security awareness programma - RT Consultancy\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/nl\\\/#website\"},\"datePublished\":\"2021-07-26T14:53:47+00:00\",\"dateModified\":\"2021-08-26T07:52:26+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/expertises\\\/security-en-crisismanagement-training\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.rtconsultancy.nl\\\/expertises\\\/security-en-crisismanagement-training\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/expertises\\\/security-en-crisismanagement-training\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rtconsultancy.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expertises\",\"item\":\"https:\\\/\\\/www.rtconsultancy.nl\\\/en\\\/expertises\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Security awareness programma\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/nl\\\/#website\",\"url\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/nl\\\/\",\"name\":\"RT Consultancy Nederland\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/nl\\\/#organization\",\"name\":\"Robrechts & Thienpont\",\"url\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rtconsultancy.nl\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Logo_1.png\",\"contentUrl\":\"https:\\\/\\\/www.rtconsultancy.nl\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Logo_1.png\",\"width\":1645,\"height\":621,\"caption\":\"Robrechts & Thienpont\"},\"image\":{\"@id\":\"http:\\\/\\\/www.rtconsultancy.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Security awareness programma - RT Consultancy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.rtconsultancy.nl\/nl\/expertises\/security-en-crisismanagement-training\/","og_locale":"nl_NL","og_type":"article","og_title":"Security awareness programma - RT Consultancy","og_description":"Een hoge betrokkenheid en het begrijpen waarom veiligheidsmaatregelen zijn ingevoerd, is voor iedere organisatie een issue. U heeft dan niet direct de behoefte aan een opleiding die uitgaat van een standaard programma en daarmee geen recht doet aan uw specifieke vraag. Een maatwerktraining, mystery visits of een workshop, die direct in de praktijk haar vruchten [&hellip;]","og_url":"http:\/\/www.rtconsultancy.nl\/nl\/expertises\/security-en-crisismanagement-training\/","og_site_name":"RT Consultancy","article_modified_time":"2021-08-26T07:52:26+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.rtconsultancy.nl\/expertises\/security-en-crisismanagement-training\/","url":"http:\/\/www.rtconsultancy.nl\/expertises\/security-en-crisismanagement-training\/","name":"Security awareness programma - RT Consultancy","isPartOf":{"@id":"http:\/\/www.rtconsultancy.nl\/nl\/#website"},"datePublished":"2021-07-26T14:53:47+00:00","dateModified":"2021-08-26T07:52:26+00:00","breadcrumb":{"@id":"http:\/\/www.rtconsultancy.nl\/expertises\/security-en-crisismanagement-training\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.rtconsultancy.nl\/expertises\/security-en-crisismanagement-training\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.rtconsultancy.nl\/expertises\/security-en-crisismanagement-training\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rtconsultancy.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Expertises","item":"https:\/\/www.rtconsultancy.nl\/en\/expertises\/"},{"@type":"ListItem","position":3,"name":"Security awareness programma"}]},{"@type":"WebSite","@id":"http:\/\/www.rtconsultancy.nl\/nl\/#website","url":"http:\/\/www.rtconsultancy.nl\/nl\/","name":"RT Consultancy Nederland","description":"","publisher":{"@id":"http:\/\/www.rtconsultancy.nl\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.rtconsultancy.nl\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"http:\/\/www.rtconsultancy.nl\/nl\/#organization","name":"Robrechts & Thienpont","url":"http:\/\/www.rtconsultancy.nl\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"http:\/\/www.rtconsultancy.nl\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.rtconsultancy.nl\/wp-content\/uploads\/2021\/08\/Logo_1.png","contentUrl":"https:\/\/www.rtconsultancy.nl\/wp-content\/uploads\/2021\/08\/Logo_1.png","width":1645,"height":621,"caption":"Robrechts & Thienpont"},"image":{"@id":"http:\/\/www.rtconsultancy.nl\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.rtconsultancy.nl\/nl\/wp-json\/wp\/v2\/expertises\/530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rtconsultancy.nl\/nl\/wp-json\/wp\/v2\/expertises"}],"about":[{"href":"https:\/\/www.rtconsultancy.nl\/nl\/wp-json\/wp\/v2\/types\/expertises"}],"version-history":[{"count":0,"href":"https:\/\/www.rtconsultancy.nl\/nl\/wp-json\/wp\/v2\/expertises\/530\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rtconsultancy.nl\/nl\/wp-json\/wp\/v2\/media?parent=530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}